{"id":36541,"date":"2021-12-14T10:46:30","date_gmt":"2021-12-14T10:46:30","guid":{"rendered":"https:\/\/pro.costa-verde.com\/?page_id=36541"},"modified":"2021-12-14T10:46:30","modified_gmt":"2021-12-14T10:46:30","slug":"proyecto-flashpor","status":"publish","type":"page","link":"https:\/\/pro.costa-verde.com\/es\/proyecto-flashpor\/","title":{"rendered":"Proyecto FLASHPor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"36541\" class=\"elementor elementor-36541 elementor-36539\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a7592e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a7592e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b7035c\" data-id=\"9b7035c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db9fd05 elementor-widget elementor-widget-spacer\" data-id=\"db9fd05\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-165daaa elementor-widget elementor-widget-heading\" data-id=\"165daaa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Proyecto FLASHPor<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6e7ced elementor-widget elementor-widget-spacer\" data-id=\"a6e7ced\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77d1fb8 elementor-widget elementor-widget-image\" data-id=\"77d1fb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"564\" height=\"170\" src=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/flashpor.jpeg.png\" class=\"attachment-large size-large wp-image-36548\" alt=\"O projeto FLASHPor tem como objetivo a utiliza\u00e7\u00e3o de tecnologia FLASH para sinteriza\u00e7\u00e3o de porcelana.\" srcset=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/flashpor.jpeg.png 564w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/flashpor.jpeg-300x90.png 300w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/flashpor.jpeg-120x36.png 120w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-508aad9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"508aad9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19deb74\" data-id=\"19deb74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-afbeebc\" data-id=\"afbeebc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f39aac8 elementor-widget elementor-widget-heading\" data-id=\"f39aac8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6c1c586\" data-id=\"6c1c586\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb3c36a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb3c36a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-546612d\" data-id=\"546612d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de76428 elementor-widget elementor-widget-spacer\" data-id=\"de76428\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5839b3a elementor-widget elementor-widget-image\" data-id=\"5839b3a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"692\" height=\"405\" src=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHSintering.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-37996\" alt=\"Tecnologia FLASH - Projeto FLASHPor: desenvolvido pela Porcelanas da Costa Verde, Universidade de Aveiro e CERINOV\" srcset=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHSintering.png 692w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHSintering-300x176.png 300w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHSintering-600x351.png 600w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHSintering-120x70.png 120w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89144e1\" data-id=\"89144e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e1d459 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"1e1d459\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8644d elementor-widget elementor-widget-text-editor\" data-id=\"fd8644d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta es la pregunta a la que pretendemos dar respuesta a trav\u00e9s del <strong>proyecto FLASHPor<\/strong>, mediante el cual investigaremos, desarrollaremos y validaremos el uso de una tecnolog\u00eda alternativa, innovadora y ambientalmente m\u00e1s sostenible para la sinterizaci\u00f3n de la porcelana durante el primer proceso de cocci\u00f3n\/bizcochar: la <strong>tecnolog\u00eda FLASH<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-686778e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"686778e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8827960\" data-id=\"8827960\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2474e6 elementor-widget elementor-widget-spacer\" data-id=\"d2474e6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24dcbcf elementor-widget elementor-widget-heading\" data-id=\"24dcbcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Proceso Convencional de Sinterizaci\u00f3n de Porcelana <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eabc703 elementor-widget elementor-widget-spacer\" data-id=\"eabc703\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea7d264 elementor-widget elementor-widget-text-editor\" data-id=\"ea7d264\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para garantizar las propiedades \u00fanicas de la porcelana, a lo largo del proceso se requieren dos o tres cocciones (cer\u00e1mica blanca o decorada) durante tiempos prolongados (m\u00e1s de 6 horas) y altas temperaturas (\u2248 1000<sup>o<\/sup>C, en la primera cocci\u00f3n\/bizcochar; m\u00e1s de 1350<sup>o<\/sup>C, en la segunda). A pesar de todos los esfuerzos por garantizar un proceso optimizado, que no comprometa el medio ambiente, sigue funcionando con combustibles f\u00f3siles, y el ciclo del bizcocho puede representar alrededor del 15% de la energ\u00eda total consumida por la planta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4249414 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4249414\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7669947\" data-id=\"7669947\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fdad6f elementor-widget elementor-widget-spacer\" data-id=\"4fdad6f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-570154d elementor-widget elementor-widget-heading\" data-id=\"570154d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo puede la tecnolog\u00eda FLASH hacer el proceso m\u00e1s sostenible?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ca3fce elementor-widget elementor-widget-spacer\" data-id=\"8ca3fce\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4175273 elementor-widget elementor-widget-text-editor\" data-id=\"4175273\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La tecnolog\u00eda FLASH utiliza un campo el\u00e9ctrico como fuerza motriz para la densificaci\u00f3n, lo que permite disminuir la dependencia de la temperatura en el proceso de cocci\u00f3n de la porcelana. Esto se aplicar\u00e1 al proceso del bizcocho, permitiendo un ciclo de sinterizaci\u00f3n m\u00e1s sostenible (disminuci\u00f3n de la temperatura y del tiempo de cocci\u00f3n).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a80d0a elementor-widget elementor-widget-spacer\" data-id=\"9a80d0a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-441c6af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"441c6af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c195e44\" data-id=\"c195e44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a80fbf elementor-widget elementor-widget-image\" data-id=\"7a80fbf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"459\" src=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-768x459.png\" class=\"attachment-medium_large size-medium_large wp-image-37992\" alt=\"FlashPor process\" srcset=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-768x459.png 768w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-300x179.png 300w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-1024x612.png 1024w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-1536x918.png 1536w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-600x359.png 600w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1-120x72.png 120w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/11\/FLASHPor_processing-1.png 1838w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac760e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac760e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6049ca1\" data-id=\"6049ca1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ef8d6 elementor-widget elementor-widget-spacer\" data-id=\"78ef8d6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c40e82 elementor-widget elementor-widget-heading\" data-id=\"0c40e82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Objetivos del Proyecto<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c42a0b6 elementor-widget elementor-widget-spacer\" data-id=\"c42a0b6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0950f26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0950f26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e5e9242\" data-id=\"e5e9242\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c5c4e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"98c5c4e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1239d2d elementor-widget elementor-widget-spacer\" data-id=\"1239d2d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbc4d26 elementor-widget elementor-widget-text-editor\" data-id=\"bbc4d26\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I+D de pastas cer\u00e1micas con composiciones adecuadas para la cocci\u00f3n, mediante la tecnolog\u00eda FLASH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fdf198a\" data-id=\"fdf198a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6b6cf elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3a6b6cf\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-sistrix\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b9d70 elementor-widget elementor-widget-text-editor\" data-id=\"46b9d70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I+D de los hornos de sinterizaci\u00f3n FLASH, concretamente con la construcci\u00f3n de un horno de pruebas de laboratorio y su ampliaci\u00f3n a un segundo horno (piloto) para la cocci\u00f3n de porcelana<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c2d1a6\" data-id=\"4c2d1a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52517ab elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"52517ab\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6aa537 elementor-widget elementor-widget-spacer\" data-id=\"a6aa537\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d68f2f elementor-widget elementor-widget-text-editor\" data-id=\"8d68f2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estudios de aplicabilidad y viabilidad industrial del proceso de sinterizaci\u00f3n FLASH de la porcelana<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16cd9c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16cd9c3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42b2c58\" data-id=\"42b2c58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2982d4 elementor-widget elementor-widget-spacer\" data-id=\"f2982d4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0f1d2e elementor-widget elementor-widget-heading\" data-id=\"c0f1d2e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Expectativas del proyecto<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31beca0 elementor-widget elementor-widget-spacer\" data-id=\"31beca0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cf524d elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9cf524d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aumento de la Sostenibilidad Ambiental del Proceso<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reducci\u00f3n Significativa de los Costes de Producci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aumento de la Cadencia Productiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aumento de la Competitividad de las Empresas del Sector<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccea3e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccea3e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-110cd9d\" data-id=\"110cd9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-000bbbb elementor-widget elementor-widget-spacer\" data-id=\"000bbbb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecbffdf lust elementor-widget elementor-widget-text-editor\" data-id=\"ecbffdf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Links<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fde23 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f7fde23\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b750bf5 elementor-widget elementor-widget-button\" data-id=\"b750bf5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Ficha_Tecnica_Projeto_FLASHPor-3.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"stroke pe-7s-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hoja T\u00e9cnica del Proyecto FlashPor (en portugu\u00e9s)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-678f130 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"678f130\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cb6cba\" data-id=\"5cb6cba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df4b82 elementor-widget elementor-widget-spacer\" data-id=\"2df4b82\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d67d69 elementor-widget elementor-widget-image\" data-id=\"3d67d69\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"117\" src=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-768x117.png\" class=\"attachment-medium_large size-medium_large wp-image-36569\" alt=\"\" srcset=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-768x117.png 768w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-300x46.png 300w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-1024x156.png 1024w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-600x91.png 600w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por-120x18.png 120w, https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/cofinanciado-por.png 1300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n La innovaci\u00f3n es uno de los motores estrat\u00e9gicos\u00a0de Costa Verde y, por eso, un \u00e1rea de conocimiento en la que la empresa ya lleva tiempo invirtiendo. Tanto para el desarrollo de un nuevo producto como para la elecci\u00f3n de nuevos equipos y sistemas de apoyo al creaci\u00f3n y la producci\u00f3n, el [&hellip;]<\/p>\n","protected":false},"author":438,"featured_media":36604,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-36541","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecto FLASHPor - Costa Verde<\/title>\n<meta name=\"description\" content=\"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pro.costa-verde.com\/projeto-flashpor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto FLASHPor - Costa Verde\" \/>\n<meta property=\"og:description\" content=\"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pro.costa-verde.com\/projeto-flashpor\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Verde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/costaverdeporcelanas\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Projeto_FLASHPor.png\" \/>\n\t<meta property=\"og:image:width\" content=\"564\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/\",\"url\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/\",\"name\":\"Proyecto FLASHPor - Costa Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pro.costa-verde.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Projeto_FLASHPor.png\",\"datePublished\":\"2021-12-14T10:46:30+00:00\",\"description\":\"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pro.costa-verde.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Projeto_FLASHPor.png\",\"contentUrl\":\"https:\\\/\\\/pro.costa-verde.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Projeto_FLASHPor.png\",\"width\":564,\"height\":200,\"caption\":\"O projeto FLASHPor tem como objetivo a utiliza\u00e7\u00e3o de tecnologia FLASH para sinteriza\u00e7\u00e3o de porcelana.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/projeto-flashpor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pro.costa-verde.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyecto FLASHPor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pro.costa-verde.com\\\/#website\",\"url\":\"https:\\\/\\\/pro.costa-verde.com\\\/\",\"name\":\"Costa Verde\",\"description\":\"Loja Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pro.costa-verde.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto FLASHPor - Costa Verde","description":"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/","og_locale":"es_ES","og_type":"article","og_title":"Proyecto FLASHPor - Costa Verde","og_description":"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!","og_url":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/","og_site_name":"Costa Verde","article_publisher":"https:\/\/www.facebook.com\/costaverdeporcelanas\/","og_image":[{"width":564,"height":200,"url":"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Projeto_FLASHPor.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/","url":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/","name":"Proyecto FLASHPor - Costa Verde","isPartOf":{"@id":"https:\/\/pro.costa-verde.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/#primaryimage"},"image":{"@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/#primaryimage"},"thumbnailUrl":"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Projeto_FLASHPor.png","datePublished":"2021-12-14T10:46:30+00:00","description":"\u00bfY si fuera posible sustituir la primera y larga cocci\u00f3n de la porcelana por un proceso de pocos minutos? La respuesta es el proyecto FLASHpor!","breadcrumb":{"@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pro.costa-verde.com\/projeto-flashpor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/#primaryimage","url":"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Projeto_FLASHPor.png","contentUrl":"https:\/\/pro.costa-verde.com\/wp-content\/uploads\/2021\/10\/Projeto_FLASHPor.png","width":564,"height":200,"caption":"O projeto FLASHPor tem como objetivo a utiliza\u00e7\u00e3o de tecnologia FLASH para sinteriza\u00e7\u00e3o de porcelana."},{"@type":"BreadcrumbList","@id":"https:\/\/pro.costa-verde.com\/projeto-flashpor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pro.costa-verde.com\/es\/"},{"@type":"ListItem","position":2,"name":"Proyecto FLASHPor"}]},{"@type":"WebSite","@id":"https:\/\/pro.costa-verde.com\/#website","url":"https:\/\/pro.costa-verde.com\/","name":"Costa Verde","description":"Loja Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pro.costa-verde.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/pages\/36541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/users\/438"}],"replies":[{"embeddable":true,"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/comments?post=36541"}],"version-history":[{"count":8,"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/pages\/36541\/revisions"}],"predecessor-version":[{"id":39114,"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/pages\/36541\/revisions\/39114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/media\/36604"}],"wp:attachment":[{"href":"https:\/\/pro.costa-verde.com\/es\/wp-json\/wp\/v2\/media?parent=36541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}